{"id":6845,"date":"2013-05-02T00:55:56","date_gmt":"2013-05-02T00:55:56","guid":{"rendered":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png"},"modified":"2013-05-02T00:55:56","modified_gmt":"2013-05-02T00:55:56","slug":"naomi-campbell-vogue-brazil-cover","status":"inherit","type":"attachment","link":"http:\/\/mytrendybuzz.com\/blog\/2013\/05\/02\/cover-trends-naomi-campbell-energizes-vogue-brazil\/naomi-campbell-vogue-brazil-cover\/","title":{"rendered":"Naomi-Campbell-Vogue-Brazil-Cover"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Naomi-Campbell-Vogue-Brazil-Cover - MyTrendyBuzz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Naomi-Campbell-Vogue-Brazil-Cover - MyTrendyBuzz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png\" \/>\n<meta property=\"og:site_name\" content=\"MyTrendyBuzz\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\",\"url\":\"https:\/\/mytrendybuzz.com\/blog\/\",\"name\":\"MyTrendyBuzz\",\"description\":\"Your destination For All Things TRENDY\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png#webpage\",\"url\":\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png\",\"name\":\"Naomi-Campbell-Vogue-Brazil-Cover - MyTrendyBuzz\",\"isPartOf\":{\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\"},\"datePublished\":\"2013-05-02T00:55:56+00:00\",\"dateModified\":\"2013-05-02T00:55:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mytrendybuzz.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cover Trends: Naomi Campbell Energizes Vogue Brazil\",\"item\":\"https:\/\/mytrendybuzz.com\/blog\/2013\/05\/02\/cover-trends-naomi-campbell-energizes-vogue-brazil\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Naomi-Campbell-Vogue-Brazil-Cover\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Naomi-Campbell-Vogue-Brazil-Cover - MyTrendyBuzz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png","og_locale":"en_US","og_type":"article","og_title":"Naomi-Campbell-Vogue-Brazil-Cover - MyTrendyBuzz","og_url":"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png","og_site_name":"MyTrendyBuzz","og_image":[{"width":448,"height":600,"url":"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/mytrendybuzz.com\/blog\/#website","url":"https:\/\/mytrendybuzz.com\/blog\/","name":"MyTrendyBuzz","description":"Your destination For All Things TRENDY","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"WebPage","@id":"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png#webpage","url":"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png","name":"Naomi-Campbell-Vogue-Brazil-Cover - MyTrendyBuzz","isPartOf":{"@id":"https:\/\/mytrendybuzz.com\/blog\/#website"},"datePublished":"2013-05-02T00:55:56+00:00","dateModified":"2013-05-02T00:55:56+00:00","breadcrumb":{"@id":"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mytrendybuzz.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cover Trends: Naomi Campbell Energizes Vogue Brazil","item":"https:\/\/mytrendybuzz.com\/blog\/2013\/05\/02\/cover-trends-naomi-campbell-energizes-vogue-brazil\/"},{"@type":"ListItem","position":3,"name":"Naomi-Campbell-Vogue-Brazil-Cover"}]}]}},"description":{"rendered":"<!-- google_ad_section_start --><p class=\"attachment\"><a href='http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png'><img width=\"300\" height=\"401\" src=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover-300x401.png\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover-300x401.png 300w, http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png 448w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<!-- google_ad_section_end -->"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":448,"height":600,"file":"2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png","sizes":{"thumbnail":{"file":"Naomi-Campbell-Vogue-Brazil-Cover-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover-150x150.png"},"medium":{"file":"Naomi-Campbell-Vogue-Brazil-Cover-300x401.png","width":300,"height":401,"mime_type":"image\/png","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover-300x401.png"},"full":{"file":"Naomi-Campbell-Vogue-Brazil-Cover.png","width":448,"height":600,"mime_type":"image\/png","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":6844,"source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2013\/05\/Naomi-Campbell-Vogue-Brazil-Cover.png","_links":{"self":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media\/6845"}],"collection":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/comments?post=6845"}]}}