{"id":5722,"date":"2012-11-29T00:56:16","date_gmt":"2012-11-29T00:56:16","guid":{"rendered":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg"},"modified":"2012-11-29T00:56:16","modified_gmt":"2012-11-29T00:56:16","slug":"unicefsnowflakeballcy-8kyi5hgfl","status":"inherit","type":"attachment","link":"http:\/\/mytrendybuzz.com\/blog\/2012\/11\/29\/trendy-fashion-report-highlights-from-the-snowflake-ball-2012\/unicefsnowflakeballcy-8kyi5hgfl\/","title":{"rendered":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unicef+SnowFlake+Ball+cy-8KYI5hGfl - MyTrendyBuzz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef%20SnowFlake%20Ball%20cy-8KYI5hGfl.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unicef+SnowFlake+Ball+cy-8KYI5hGfl - MyTrendyBuzz\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef SnowFlake Ball cy-8KYI5hGfl.jpg\" \/>\n<meta property=\"og:site_name\" content=\"MyTrendyBuzz\" \/>\n<meta property=\"og:image\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"319\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\",\"url\":\"https:\/\/mytrendybuzz.com\/blog\/\",\"name\":\"MyTrendyBuzz\",\"description\":\"Your destination For All Things TRENDY\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg#webpage\",\"url\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg\",\"name\":\"Unicef+SnowFlake+Ball+cy-8KYI5hGfl - MyTrendyBuzz\",\"isPartOf\":{\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\"},\"datePublished\":\"2012-11-29T00:56:16+00:00\",\"dateModified\":\"2012-11-29T00:56:16+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mytrendybuzz.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trendy Fashion Report: Highlights from the Snowflake Ball 2012\",\"item\":\"http:\/\/mytrendybuzz.com\/blog\/2012\/11\/29\/trendy-fashion-report-highlights-from-the-snowflake-ball-2012\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unicef+SnowFlake+Ball+cy-8KYI5hGfl\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl - MyTrendyBuzz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef SnowFlake Ball cy-8KYI5hGfl.jpg","og_locale":"en_US","og_type":"article","og_title":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl - MyTrendyBuzz","og_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef SnowFlake Ball cy-8KYI5hGfl.jpg","og_site_name":"MyTrendyBuzz","og_image":[{"width":"319","height":"480","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/mytrendybuzz.com\/blog\/#website","url":"https:\/\/mytrendybuzz.com\/blog\/","name":"MyTrendyBuzz","description":"Your destination For All Things TRENDY","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"WebPage","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg#webpage","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg","name":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl - MyTrendyBuzz","isPartOf":{"@id":"https:\/\/mytrendybuzz.com\/blog\/#website"},"datePublished":"2012-11-29T00:56:16+00:00","dateModified":"2012-11-29T00:56:16+00:00","breadcrumb":{"@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mytrendybuzz.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Trendy Fashion Report: Highlights from the Snowflake Ball 2012","item":"http:\/\/mytrendybuzz.com\/blog\/2012\/11\/29\/trendy-fashion-report-highlights-from-the-snowflake-ball-2012\/"},{"@type":"ListItem","position":3,"name":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl"}]}]}},"description":{"rendered":"<!-- google_ad_section_start --><p class=\"attachment\"><a href='http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg'><img width=\"300\" height=\"451\" src=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl-300x451.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl-300x451.jpg 300w, http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg 319w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<!-- google_ad_section_end -->"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"319","height":"480","hwstring_small":"height='96' width='63'","file":"2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg","sizes":{"thumbnail":{"file":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl-150x150.jpg","width":"150","height":"150","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl-150x150.jpg"},"medium":{"file":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl-300x451.jpg","width":"300","height":"451","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl-300x451.jpg"},"full":{"file":"Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg","width":319,"height":480,"mime_type":"image\/jpeg","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":5720,"source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/11\/Unicef+SnowFlake+Ball+cy-8KYI5hGfl.jpg","_links":{"self":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media\/5722"}],"collection":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/comments?post=5722"}]}}