{"id":5238,"date":"2012-10-17T00:49:51","date_gmt":"2012-10-17T00:49:51","guid":{"rendered":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg"},"modified":"2012-10-17T00:49:51","modified_gmt":"2012-10-17T00:49:51","slug":"eye-wih05","status":"inherit","type":"attachment","link":"http:\/\/mytrendybuzz.com\/blog\/2012\/10\/17\/trendy-fashion-report-highlights-from-elle-magazines-women-in-hollywood-event\/eye-wih05\/","title":{"rendered":"eye-wih05"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>eye-wih05 - MyTrendyBuzz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eye-wih05 - MyTrendyBuzz\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg\" \/>\n<meta property=\"og:site_name\" content=\"MyTrendyBuzz\" \/>\n<meta property=\"og:image\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\",\"url\":\"https:\/\/mytrendybuzz.com\/blog\/\",\"name\":\"MyTrendyBuzz\",\"description\":\"Your destination For All Things TRENDY\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg#webpage\",\"url\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg\",\"name\":\"eye-wih05 - MyTrendyBuzz\",\"isPartOf\":{\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\"},\"datePublished\":\"2012-10-17T00:49:51+00:00\",\"dateModified\":\"2012-10-17T00:49:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mytrendybuzz.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trendy Fashion Report: Highlights from Elle Magazine&#8217;s Women in Hollywood Event\",\"item\":\"http:\/\/mytrendybuzz.com\/blog\/2012\/10\/17\/trendy-fashion-report-highlights-from-elle-magazines-women-in-hollywood-event\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"eye-wih05\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"eye-wih05 - MyTrendyBuzz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg","og_locale":"en_US","og_type":"article","og_title":"eye-wih05 - MyTrendyBuzz","og_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg","og_site_name":"MyTrendyBuzz","og_image":[{"width":"683","height":"1024","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/mytrendybuzz.com\/blog\/#website","url":"https:\/\/mytrendybuzz.com\/blog\/","name":"MyTrendyBuzz","description":"Your destination For All Things TRENDY","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"WebPage","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg#webpage","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg","name":"eye-wih05 - MyTrendyBuzz","isPartOf":{"@id":"https:\/\/mytrendybuzz.com\/blog\/#website"},"datePublished":"2012-10-17T00:49:51+00:00","dateModified":"2012-10-17T00:49:51+00:00","breadcrumb":{"@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mytrendybuzz.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Trendy Fashion Report: Highlights from Elle Magazine&#8217;s Women in Hollywood Event","item":"http:\/\/mytrendybuzz.com\/blog\/2012\/10\/17\/trendy-fashion-report-highlights-from-elle-magazines-women-in-hollywood-event\/"},{"@type":"ListItem","position":3,"name":"eye-wih05"}]}]}},"description":{"rendered":"<!-- google_ad_section_start --><p class=\"attachment\"><a href='http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg'><img width=\"300\" height=\"449\" src=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05-300x449.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05-300x449.jpg 300w, http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05-620x929.jpg 620w, http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg 683w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<!-- google_ad_section_end -->"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"683","height":"1024","hwstring_small":"height='96' width='64'","file":"2012\/10\/eye-wih05.jpg","sizes":{"thumbnail":{"file":"eye-wih05-150x150.jpg","width":"150","height":"150","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05-150x150.jpg"},"medium":{"file":"eye-wih05-300x449.jpg","width":"300","height":"449","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05-300x449.jpg"},"large":{"file":"eye-wih05-620x929.jpg","width":"620","height":"929","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05-620x929.jpg"},"full":{"file":"eye-wih05.jpg","width":683,"height":1024,"mime_type":"image\/jpeg","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":5231,"source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/10\/eye-wih05.jpg","_links":{"self":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media\/5238"}],"collection":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/comments?post=5238"}]}}