{"id":4213,"date":"2012-08-16T23:15:57","date_gmt":"2012-08-16T23:15:57","guid":{"rendered":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg"},"modified":"2012-08-16T23:15:57","modified_gmt":"2012-08-16T23:15:57","slug":"celebrities-madonna-1719184","status":"inherit","type":"attachment","link":"http:\/\/mytrendybuzz.com\/blog\/2012\/08\/16\/trendy-celeb-spotlight-happy-birthday-madonna\/celebrities-madonna-1719184\/","title":{"rendered":"celebrities-madonna-1719184"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>celebrities-madonna-1719184 - MyTrendyBuzz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"celebrities-madonna-1719184 - MyTrendyBuzz\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg\" \/>\n<meta property=\"og:site_name\" content=\"MyTrendyBuzz\" \/>\n<meta property=\"og:image\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\",\"url\":\"https:\/\/mytrendybuzz.com\/blog\/\",\"name\":\"MyTrendyBuzz\",\"description\":\"Your destination For All Things TRENDY\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg#webpage\",\"url\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg\",\"name\":\"celebrities-madonna-1719184 - MyTrendyBuzz\",\"isPartOf\":{\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\"},\"datePublished\":\"2012-08-16T23:15:57+00:00\",\"dateModified\":\"2012-08-16T23:15:57+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mytrendybuzz.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trendy Celeb Spotlight: Happy Birthday Madonna!\",\"item\":\"http:\/\/mytrendybuzz.com\/blog\/2012\/08\/16\/trendy-celeb-spotlight-happy-birthday-madonna\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"celebrities-madonna-1719184\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"celebrities-madonna-1719184 - MyTrendyBuzz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg","og_locale":"en_US","og_type":"article","og_title":"celebrities-madonna-1719184 - MyTrendyBuzz","og_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg","og_site_name":"MyTrendyBuzz","og_image":[{"width":"400","height":"500","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/mytrendybuzz.com\/blog\/#website","url":"https:\/\/mytrendybuzz.com\/blog\/","name":"MyTrendyBuzz","description":"Your destination For All Things TRENDY","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"WebPage","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg#webpage","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg","name":"celebrities-madonna-1719184 - MyTrendyBuzz","isPartOf":{"@id":"https:\/\/mytrendybuzz.com\/blog\/#website"},"datePublished":"2012-08-16T23:15:57+00:00","dateModified":"2012-08-16T23:15:57+00:00","breadcrumb":{"@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mytrendybuzz.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Trendy Celeb Spotlight: Happy Birthday Madonna!","item":"http:\/\/mytrendybuzz.com\/blog\/2012\/08\/16\/trendy-celeb-spotlight-happy-birthday-madonna\/"},{"@type":"ListItem","position":3,"name":"celebrities-madonna-1719184"}]}]}},"description":{"rendered":"<!-- google_ad_section_start --><p class=\"attachment\"><a href='http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg'><img width=\"300\" height=\"375\" src=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841-300x375.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841-300x375.jpg 300w, http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<!-- google_ad_section_end -->"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"400","height":"500","hwstring_small":"height='96' width='76'","file":"2012\/08\/celebrities-madonna-17191841.jpg","sizes":{"thumbnail":{"file":"celebrities-madonna-17191841-150x150.jpg","width":"150","height":"150","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841-150x150.jpg"},"medium":{"file":"celebrities-madonna-17191841-300x375.jpg","width":"300","height":"375","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841-300x375.jpg"},"full":{"file":"celebrities-madonna-17191841.jpg","width":400,"height":500,"mime_type":"image\/jpeg","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":4198,"source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/08\/celebrities-madonna-17191841.jpg","_links":{"self":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media\/4213"}],"collection":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/comments?post=4213"}]}}