{"id":3109,"date":"2012-05-31T02:27:40","date_gmt":"2012-05-31T02:27:40","guid":{"rendered":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg"},"modified":"2012-05-31T02:27:40","modified_gmt":"2012-05-31T02:27:40","slug":"mad-men_banana-republic1","status":"inherit","type":"attachment","link":"http:\/\/mytrendybuzz.com\/blog\/2012\/05\/31\/mad-men-is-mad-good-for-banana-republic\/mad-men_banana-republic1\/","title":{"rendered":"Mad-Men_Banana-Republic+1"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mad-Men_Banana-Republic+1 - MyTrendyBuzz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic%201.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mad-Men_Banana-Republic+1 - MyTrendyBuzz\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic 1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"MyTrendyBuzz\" \/>\n<meta property=\"og:image\" content=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\",\"url\":\"https:\/\/mytrendybuzz.com\/blog\/\",\"name\":\"MyTrendyBuzz\",\"description\":\"Your destination For All Things TRENDY\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg#webpage\",\"url\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg\",\"name\":\"Mad-Men_Banana-Republic+1 - MyTrendyBuzz\",\"isPartOf\":{\"@id\":\"https:\/\/mytrendybuzz.com\/blog\/#website\"},\"datePublished\":\"2012-05-31T02:27:40+00:00\",\"dateModified\":\"2012-05-31T02:27:40+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mytrendybuzz.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mad Men is Mad Good for Banana Republic\",\"item\":\"http:\/\/mytrendybuzz.com\/blog\/2012\/05\/31\/mad-men-is-mad-good-for-banana-republic\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mad-Men_Banana-Republic+1\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mad-Men_Banana-Republic+1 - MyTrendyBuzz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic 1.jpg","og_locale":"en_US","og_type":"article","og_title":"Mad-Men_Banana-Republic+1 - MyTrendyBuzz","og_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic 1.jpg","og_site_name":"MyTrendyBuzz","og_image":[{"width":"800","height":"640","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/mytrendybuzz.com\/blog\/#website","url":"https:\/\/mytrendybuzz.com\/blog\/","name":"MyTrendyBuzz","description":"Your destination For All Things TRENDY","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mytrendybuzz.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"WebPage","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg#webpage","url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg","name":"Mad-Men_Banana-Republic+1 - MyTrendyBuzz","isPartOf":{"@id":"https:\/\/mytrendybuzz.com\/blog\/#website"},"datePublished":"2012-05-31T02:27:40+00:00","dateModified":"2012-05-31T02:27:40+00:00","breadcrumb":{"@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mytrendybuzz.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mad Men is Mad Good for Banana Republic","item":"http:\/\/mytrendybuzz.com\/blog\/2012\/05\/31\/mad-men-is-mad-good-for-banana-republic\/"},{"@type":"ListItem","position":3,"name":"Mad-Men_Banana-Republic+1"}]}]}},"description":{"rendered":"<!-- google_ad_section_start --><p class=\"attachment\"><a href='http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg'><img width=\"300\" height=\"240\" src=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1-300x240.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1-300x240.jpg 300w, http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1-620x496.jpg 620w, http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<!-- google_ad_section_end -->"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"800","height":"640","hwstring_small":"height='96' width='120'","file":"2012\/05\/Mad-Men_Banana-Republic+1.jpg","sizes":{"thumbnail":{"file":"Mad-Men_Banana-Republic+1-150x150.jpg","width":"150","height":"150","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1-150x150.jpg"},"medium":{"file":"Mad-Men_Banana-Republic+1-300x240.jpg","width":"300","height":"240","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1-300x240.jpg"},"large":{"file":"Mad-Men_Banana-Republic+1-620x496.jpg","width":"620","height":"496","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1-620x496.jpg"},"full":{"file":"Mad-Men_Banana-Republic+1.jpg","width":800,"height":640,"mime_type":"image\/jpeg","source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":3108,"source_url":"http:\/\/mytrendybuzz.com\/blog\/wp-content\/uploads\/2012\/05\/Mad-Men_Banana-Republic+1.jpg","_links":{"self":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media\/3109"}],"collection":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/mytrendybuzz.com\/blog\/wp-json\/wp\/v2\/comments?post=3109"}]}}